{"id":6664,"date":"2023-09-27T00:00:00","date_gmt":"2023-09-27T00:00:00","guid":{"rendered":"https:\/\/lovesleepee.com\/?p=6664"},"modified":"2024-10-14T06:32:00","modified_gmt":"2024-10-14T06:32:00","slug":"warum-ist-umarmen-wichtig","status":"publish","type":"post","link":"https:\/\/lovesleepee.com\/de\/warum-ist-umarmen-wichtig\/","title":{"rendered":"Warum ist eine Umarmung wichtig?"},"content":{"rendered":"<p>Im Mutterleib wird das Baby von den weichen W\u00e4nden der Geb\u00e4rmutter umh\u00fcllt. Der K\u00f6rper des Babys wird von Anfang an durch Ber\u00fchrungen stimuliert. Nach der Geburt wird das Baby in die liebevollen Arme seiner Mutter gelegt. Der erste Haut-zu-Haut-Kontakt ist der wichtigste Moment im Leben des Kleinen. Kurz nach der Geburt trocknet die Hebamme das Kind ab und legt es an die Brust der Mutter, dann wickelt sie es ein, um es vor W\u00e4rmeverlust zu sch\u00fctzen. Der K\u00f6rper der Mutter ist in der Lage, die Temperatur dort zu erh\u00f6hen, wo das Baby liegt, um es zu w\u00e4rmen. F\u00fcr das Neugeborene ist alles neu, die Ber\u00fchrungen, Ger\u00fcche, Ger\u00e4usche, das Licht, die niedrigere Temperatur. Das Baby auf dem Bauch der Mutter nimmt die neuen Bedingungen leichter an, h\u00f6rt ihren Herzschlag, riecht ihre Haut und bekommt gleich die ersten Tropfen Kolostrum, einen nat\u00fcrlichen \"Impfstoff\". Unter dem Einfluss der Hormone verliebt sich die Mutter in das Baby, auch wenn sie sich zuvor gefragt hat, ob sie der neuen Rolle gewachsen ist. K\u00f6rperliche N\u00e4he ist entscheidend f\u00fcr den Aufbau von Bindungen, sowohl zwischen Mutter und Kind als auch in jedem sp\u00e4teren Lebensabschnitt in den Beziehungen zu anderen Menschen. Verantwortlich daf\u00fcr ist zu einem gro\u00dfen Teil das als Liebeshormon bekannte Oxytocin, das unter dem Einfluss von Umarmungen im Gehirn ausgesch\u00fcttet wird. Umarmung und F\u00fcrsorge sorgen f\u00fcr einen kontinuierlichen, erh\u00f6hten Oxytocinspiegel beim Kind, der ein Gef\u00fchl der Sicherheit vermittelt und Stresshormone abbaut. Das Baby ist ruhiger, schl\u00e4ft besser und l\u00e4nger, l\u00e4sst sich leichter f\u00fcttern, und die Pflege des Babys ist f\u00fcr die Eltern nicht so anstrengend.<\/p>\n<p><strong>Vergessen wir den Vater nicht!<\/strong><\/p>\n<p>Das Umarmen des Vaters mit dem Baby baut eine Bindung auf und erleichtert den \u00dcbergang in eine neue Rolle. M\u00e4nner, die mit ihren Kindern schmusen, sind sensibler f\u00fcr deren Bed\u00fcrfnisse und eher bereit, bei dem Kind zu bleiben, damit die Mutter das Haus verlassen kann. M\u00e4nner, die bei einem Kaiserschnitt Haut-zu-Haut-Kontakt mit einem Neugeborenen hatten, sind st\u00e4rker in die Pflege des Babys eingebunden, und die Babys sind ruhiger, weinen weniger und schlafen besser.<\/p>\n<p>Und jetzt kommst du nach Hause und h\u00f6rst: \"Nicht schaukeln, nicht tragen, denn er wird sich daran gew\u00f6hnen\", aber nichts k\u00f6nnte weiter von der Wahrheit entfernt sein. Schlie\u00dflich hatte er keine Zeit, sich selbst zu entw\u00f6hnen, und er wurde die ganze Schwangerschaft \u00fcber im Bauch seiner Mutter geschaukelt, sanft massiert vom umgebenden Fruchtwasser. Babys terrorisieren nicht, sie melden Bed\u00fcrfnisse, und wenn die Eltern diese Bed\u00fcrfnisse erf\u00fcllen, sind Babys \"leichter zu handhaben\".<\/p>\n<p>Umarmen senkt den Stresshormonspiegel des Babys und regt die Aussch\u00fcttung von Endorphinen an. Das sind nat\u00fcrliche Opioide, die das Schmerzempfinden verringern und ein Gef\u00fchl der Freude vermitteln.<\/p>\n<p><strong>Zusammenfassen, warum kuscheln?<\/strong><\/p>\n<p>Kinder, die umarmt werden, f\u00fchlen sich geliebt und angenommen und k\u00f6nnen R\u00fcckschl\u00e4ge, Unf\u00e4lle und kleinere Verletzungen leichter verkraften.<\/p>\n<p>Sie kommen sp\u00e4ter im Leben leichter zurecht, sind mutiger, selbstbewusster und entwickeln sich schneller.<\/p>\n<p>Umarmen ist verantwortlich f\u00fcr die emotionale Entwicklung eines Kindes<\/p>\n<p><strong>Ber\u00fchrung f\u00f6rdert die Entwicklung der Intelligenz, indem sie die Anzahl der Verbindungen zwischen den Zellen im Gehirn erh\u00f6ht<\/strong>.<\/p>\n<p>S\u00e4uglinge nehmen mehr als 80% der Reize durch Ber\u00fchrung auf, was bedeutet, dass sie etwas \u00fcber die Welt lernen<\/p>\n<p>Umarmen f\u00f6rdert die Entwicklung und Funktion des Herz-Kreislauf-Systems und der Atemwege und verbessert die Immunit\u00e4t.<\/p>\n<p>Umarmen ist auch f\u00fcr Erwachsene wichtig. Die Britische Herzstiftung<br \/>\nOrganisation f\u00fchrte eine Studie durch, die zeigte, dass <strong>Eine Umarmung von nur 20 Sekunden baut nicht nur Stress ab, sondern hat auch eine positive Wirkung auf das Herz: Sie senkt die Herzfrequenz und den Blutdruck und st\u00e4rkt die Gehirnfunktion.<\/strong><\/p>\n<p><strong>Lasst uns<br \/>\nKuscheln <\/strong><\/p>\n<p><strong>12 Mal am Tag, um sich richtig zu entwickeln<\/strong><\/p>\n<p>.<\/p>\n<p><strong>8 Mal am Tag, um gesund zu bleiben<\/strong><\/p>\n<p><strong>4 Mal am Tag, um zu \u00fcberleben<\/strong><\/p>\n<p>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Im Mutterleib wird das Baby von den weichen W\u00e4nden der Geb\u00e4rmutter umh\u00fcllt. Der K\u00f6rper des Babys wird stimuliert<\/p>","protected":false},"author":4,"featured_media":7460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[833],"tags":[],"class_list":["post-6664","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-parenting-tips-advice"],"_links":{"self":[{"href":"https:\/\/lovesleepee.com\/de\/wp-json\/wp\/v2\/posts\/6664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lovesleepee.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lovesleepee.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lovesleepee.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lovesleepee.com\/de\/wp-json\/wp\/v2\/comments?post=6664"}],"version-history":[{"count":0,"href":"https:\/\/lovesleepee.com\/de\/wp-json\/wp\/v2\/posts\/6664\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lovesleepee.com\/de\/wp-json\/wp\/v2\/media\/7460"}],"wp:attachment":[{"href":"https:\/\/lovesleepee.com\/de\/wp-json\/wp\/v2\/media?parent=6664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lovesleepee.com\/de\/wp-json\/wp\/v2\/categories?post=6664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lovesleepee.com\/de\/wp-json\/wp\/v2\/tags?post=6664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}